{"id":1965,"date":"2024-10-15T13:55:10","date_gmt":"2024-10-15T11:55:10","guid":{"rendered":"https:\/\/talentagestion.es\/talenta-incorpora-a-merche-grau-como-socia-y-consejera-ejecutiva\/"},"modified":"2024-11-20T12:26:07","modified_gmt":"2024-11-20T11:26:07","slug":"talenta-incorpora-a-merche-grau-como-socia-y-consejera-ejecutiva","status":"publish","type":"post","link":"https:\/\/talentagestion.es\/ca\/talenta-incorpora-a-merche-grau-como-socia-y-consejera-ejecutiva\/","title":{"rendered":"TALENTA\u00a0INCORPORA A\u00a0MERCHE\u00a0GRAU COM A S\u00d2CIA I CONSELLERA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La gestora independent presidida per Jordi&nbsp;Jofre&nbsp;aferma &nbsp;el seu lideratge a Catalunya aconseguint els 1.567 milions assessorats<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Talenta&nbsp;SGIIC&nbsp;incorpora a&nbsp;Merche&nbsp;Grau en el seu equip com a s\u00f2cia i consellera no executiva. Grau, professional referent en el sector, se suma a l&#8217;equip de l&#8217;entitat poc abans de tancar un any r\u00e8cord, tant en facturaci\u00f3 com en patrimoni assessorat, afermant a&nbsp;Talenta&nbsp;com a l\u00edder del sector de les gestores de patrimoni independents a Catalunya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amb una \u00e0mplia experi\u00e8ncia professional en l&#8217;\u00e0mbit financer i d&#8217;assessorament patrimonial a Espanya,&nbsp;Merche&nbsp;Grau va ser Directora General en Banca March i va formar part del Comit\u00e8 de Direcci\u00f3 de Catalunya Caixa liderant la Banca Privada i Gesti\u00f3 d&#8217;Actius. En els seus inicis va ocupar posats s\u00e8nior a nivell europeu, en&nbsp;Merrill&nbsp;Lynch i&nbsp;Credit&nbsp;Suisse. En els \u00faltims 7 anys ha estat Consellera i membre del Comit\u00e8 de Direcci\u00f3 de&nbsp;MdF&nbsp;Family&nbsp;Partners, dirigint el negoci de l&#8217;entitat a Catalunya. A m\u00e9s, en aquest temps s&#8217;ha incorporat com a consellera independent en diverses companyies entre les quals destaquen,&nbsp;Trea&nbsp;AM,&nbsp;Boyser&nbsp;CP,&nbsp;Logisfashion,&nbsp;Elix&nbsp;Rental&nbsp;Housing&nbsp;Socimi&nbsp;i Grup&nbsp;Elix. Llicenciada en&nbsp;ADE&nbsp;i MBA per&nbsp;ESADE, Mercedes Grau compta amb un Programa en&nbsp;International&nbsp;Management en&nbsp;Bocconi&nbsp;University&nbsp;(Mil\u00e0) i un Programa en Direcci\u00f3 Internacional en&nbsp;Stockholm&nbsp;School&nbsp;of&nbsp;Economics&nbsp;(Su\u00e8cia), amb especialitat en Finances Internacionals.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grau defineix el seu nou repte professional com una aposta per un projecte guanyador:&nbsp; \u00abAmb una llarga experi\u00e8ncia laboral, aquest \u00e9s l&#8217;inici d&#8217;una nova etapa apassionant\u00bb, afirma. \u00abEm sumo a&nbsp;Talenta&nbsp;perqu\u00e8 crec en l&#8217;enfocament d&#8217;aquest projecte. Porto molts anys treballant en el sector i conec perfectament les necessitats dels clients\u00bb, afegeix. La nova s\u00f2cia i consellera executiva defineix a&nbsp;Talenta&nbsp;com un l\u00edder en ple creixement. \u00abTalenta&nbsp;\u00e9s l\u00edder en assessorament patrimonial independent i ho \u00e9s perqu\u00e8 ofereix el servei personalitzat que necessiten els clients, empresaris i emprenedors a Catalunya per a avan\u00e7ar\u00bb. &nbsp;Per al president de&nbsp;Talenta, Jordi&nbsp;Jofre, la incorporaci\u00f3 de Grau \u00e9s implica \u201cun creixement estrat\u00e8gic per a afermar el lideratge&nbsp; de&nbsp;Talenta&nbsp;com a gestora independent de patrimonis a Catalunya\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En l&#8217;actualitat,&nbsp;Talenta&nbsp;gestiona 1.567 milions d&#8217;euros, la major xifra des de la fundaci\u00f3 de la companyia. A m\u00e9s, enguany aconseguir\u00e0 tancar-ho amb una facturaci\u00f3 r\u00e8cord de 6 milions d&#8217;euros i finalitzar\u00e0 el 2024 amb 21 entitats regulades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOBRE TALENTA:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Talenta&nbsp;\u00e9s una entitat financera independent fundada en 2009 i inscrita en els registres de la Comissi\u00f3 Nacional del Mercat de Valors com a Societat Gestora d&#8217;Institucions d&#8217;Inversi\u00f3 Col\u00b7lectiva (SGIIC). La companyia est\u00e0 formada per experts dedicats a la gesti\u00f3 i l&#8217;assessorament patrimonial independent, proporcionant serveis de&nbsp;multi&nbsp;Family&nbsp;Office i assessorament financer i d&#8217;inversions a clients de Banca Privada. A m\u00e9s, est\u00e0 especialitzada en inversions alternatives en diversos sectors com l&#8217;immobiliari, el&nbsp;venture&nbsp;capital, el&nbsp;private&nbsp;equity&nbsp;i les energies renovables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La seu central de&nbsp;Talenta&nbsp;est\u00e0 a Barcelona i compta amb oficines a Val\u00e8ncia i Palma. Entre les tres seus, suma un total de 28 professionals.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gestora independent presidida per Jordi&nbsp;Jofre&nbsp;aferma &nbsp;el seu lideratge a Catalunya aconseguint els 1.567 milions assessorats Talenta&nbsp;SGIIC&nbsp;incorpora a&nbsp;Merche&nbsp;Grau en el seu equip com a s\u00f2cia i consellera no executiva. Grau, professional referent en el sector, se suma a l&#8217;equip de l&#8217;entitat poc abans de tancar un any r\u00e8cord, tant en facturaci\u00f3 com en patrimoni assessorat, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[65,66,67],"class_list":["post-1965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","tag-jordi-jofre-ca","tag-mercedes-grau-ca","tag-talenta-gestion-ca"],"acf":[],"_links":{"self":[{"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/posts\/1965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/comments?post=1965"}],"version-history":[{"count":0,"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/posts\/1965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/media\/1707"}],"wp:attachment":[{"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/media?parent=1965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/categories?post=1965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/talentagestion.es\/ca\/wp-json\/wp\/v2\/tags?post=1965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}